{"id":18170,"date":"2021-10-06T17:52:10","date_gmt":"2021-10-06T17:52:10","guid":{"rendered":"https:\/\/altos-klinika.cz\/all-procedures\/"},"modified":"2026-06-24T15:04:21","modified_gmt":"2026-06-24T15:04:21","slug":"all-procedures","status":"publish","type":"page","link":"https:\/\/altos-klinika.cz\/de\/all-procedures\/","title":{"rendered":"All procedures"},"content":{"rendered":"<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<html><body><div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][\/vc_column][\/vc_row][vc_row simple_background_color=\"#fafafa\"][vc_column]<\/p><div class=\"mkdf-elements-holder mkdf-one-column mkdf-responsive-mode-768\"><div class=\"mkdf-eh-item mkdf-horizontal-alignment-center\" data-item-class=\"mkdf-eh-custom-838875\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-838875\" style=\"padding: 100px 0px 0px 0px\">\n\t\t\t<div class=\"mkdf-section-title-holder mkdf-st-standard mkdf-st-title-left mkdf-st-normal-space \">\n\t<div class=\"mkdf-st-inner\">\n\t\t\t\t\t<h2 class=\"mkdf-st-title\">\n\t\t\t\tDie gefragtesten Prozeduren\t\t\t<\/h2>\n\t\t\t\t\t<\/div>\n<\/div>[vc_column_text]\n<p style=\"text-align: center;\">Prozeduren, die Sie interessieren k\u00f6nnten<\/p>\n<p>[\/vc_column_text]\t\t<\/p><\/div>\n\t<\/div>\n<\/div><\/div>[vc_row_inner content_text_aligment=\"center\" css=\".vc_custom_1635020125633{padding-top: 20px !important;padding-right: 20px !important;padding-bottom: 20px !important;padding-left: 20px !important;}\"][vc_column_inner css=\".vc_custom_1633645017807{padding-top: 5% !important;padding-right: 5% !important;padding-bottom: 5% !important;padding-left: 5% !important;}\" offset=\"vc_col-lg-3 vc_col-md-6 vc_col-sm-offset-0 vc_col-xs-12\"]<div class=\"mkdf-elements-holder mkdf-one-column mkdf-responsive-mode-768\"><div class=\"mkdf-eh-item mkdf-horizontal-alignment-center\" style=\"background-color: #ffffff\" data-item-class=\"mkdf-eh-custom-502344\" data-1280-1600=\"30px\" data-1024-1280=\"30px\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-502344\" style=\"padding: 30px\">\n\t\t\t[vc_column_text]\n<h5>Laserepilation<\/h5>\n<p>Die Laser-Haarentfernung entfernt unerw\u00fcnschte Haare nicht nur am K\u00f6rper, sondern auch im Gesicht. Eine effektive L\u00f6sung f\u00fcr glatte Haut. Ein sicherer Weg, um dauerhafte Haare loszuwerden.[\/vc_column_text][vc_empty_space][vc_column_text css=\"\"]<\/p>\n<p style=\"text-align: center; margin-top: 10px;\"><a class=\"mkdf-btn mkdf-btn-medium mkdf-btn-outline\" style=\"color: #43d5cb; padding: 14px 30px; border: 1px solid #43d5cb; border-radius: 5px; font-weight: 300;\" href=\"https:\/\/altos-klinika.cz\/de\/laser-hair-removal\/\" target=\"_self\" rel=\"noopener\">Mehr Info<\/a><\/p>\n<p>[\/vc_column_text]\t\t<\/p><\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column_inner][vc_column_inner css=\".vc_custom_1633640981984{padding-top: 5% !important;padding-right: 5% !important;padding-bottom: 5% !important;padding-left: 5% !important;}\" offset=\"vc_col-lg-3 vc_col-md-6 vc_col-xs-12\"]<div class=\"mkdf-elements-holder mkdf-one-column mkdf-responsive-mode-768\"><div class=\"mkdf-eh-item mkdf-horizontal-alignment-center\" style=\"background-color: #ffffff\" data-item-class=\"mkdf-eh-custom-101440\" data-1280-1600=\"30px\" data-1024-1280=\"30px\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-101440\" style=\"padding: 30px\">\n\t\t\t[vc_column_text]\n<h5>Fractional Laser Resurfacing<\/h5>\n<p>Fractional Resurfacing ist eine ideale Wahl f\u00fcr alternde oder gesch\u00e4digte Haut. Es wirkt auf die Oberfl\u00e4che der oberen Schicht, stimuliert gleichzeitig das Wachstum neuer Hautzellen und die Bildung von neuem Kollagen und startet so den nat\u00fcrlichen Heilungsprozess.[\/vc_column_text][vc_empty_space][vc_column_text css=\"\"]<\/p>\n<p style=\"text-align: center; margin-top: 10px;\"><a class=\"mkdf-btn mkdf-btn-medium mkdf-btn-outline\" style=\"color: #43d5cb; padding: 14px 30px; border: 1px solid #43d5cb; border-radius: 5px; font-weight: 300;\" href=\"https:\/\/altos-klinika.cz\/de\/laser-resurfacing\/\" target=\"_self\" rel=\"noopener\">Mehr Info<\/a><\/p>\n<p>[\/vc_column_text]\t\t<\/p><\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column_inner][vc_column_inner css=\".vc_custom_1633640989450{padding-top: 5% !important;padding-right: 5% !important;padding-bottom: 5% !important;padding-left: 5% !important;}\" offset=\"vc_col-lg-3 vc_col-md-6 vc_col-xs-12\"]<div class=\"mkdf-elements-holder mkdf-one-column mkdf-responsive-mode-768\"><div class=\"mkdf-eh-item mkdf-horizontal-alignment-center\" style=\"background-color: #ffffff\" data-item-class=\"mkdf-eh-custom-964765\" data-1280-1600=\"55px 15%\" data-1024-1280=\"55px 15%\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-964765\" style=\"padding: 30px\">\n\t\t\t[vc_column_text]\n<h5>Behandlung von Hyperhidrose (L\u00f6sung von \u00fcberm\u00e4\u00dfigem Schwitzen)<\/h5>\n<p>Reduzierung von \u00fcberm\u00e4\u00dfigem Schwitzen an Achseln, Handfl\u00e4chen, F\u00fc\u00dfen oder Fu\u00dfsohlen mit Hilfe einer Injektion von Botulinumtoxin Typ A. Die Wirkung h\u00e4lt bis zu 12 Monate an.[\/vc_column_text][vc_empty_space][vc_column_text css=\"\"]<\/p>\n<p style=\"text-align: center; margin-top: 10px;\"><a class=\"mkdf-btn mkdf-btn-medium mkdf-btn-outline\" style=\"color: #43d5cb; padding: 14px 30px; border: 1px solid #43d5cb; border-radius: 5px; font-weight: 300;\" href=\"https:\/\/altos-klinika.cz\/de\/hyperhidrosis-treatment\/\" target=\"_self\" rel=\"noopener\">Mehr Info<\/a><\/p>\n<p>[\/vc_column_text]\t\t<\/p><\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column_inner][vc_column_inner css=\".vc_custom_1633641007684{padding-top: 5% !important;padding-right: 5% !important;padding-bottom: 5% !important;padding-left: 5% !important;}\" offset=\"vc_col-lg-3 vc_col-md-6 vc_col-xs-12\"]<div class=\"mkdf-elements-holder mkdf-one-column mkdf-responsive-mode-768\"><div class=\"mkdf-eh-item mkdf-horizontal-alignment-center\" style=\"background-color: #ffffff\" data-item-class=\"mkdf-eh-custom-124155\" data-1280-1600=\"55px 15%\" data-1024-1280=\"55px 15%\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-124155\" style=\"padding: 30px\">\n\t\t\t[vc_column_text]\n<h5>Hochfrequenz-K\u00f6rperlifting<\/h5>\n<p>RF Bodylifting mit dem TriActive+ Ger\u00e4t zur schnellen K\u00f6rperkorrektur und Reduzierung \u00fcbersch\u00fcssiger Fettp\u00f6lsterchen. Die Methode ist nicht-invasiv und f\u00fcr alle Hauttypen geeignet.[\/vc_column_text][vc_empty_space][vc_column_text css=\"\"]<\/p>\n<p style=\"text-align: center; margin-top: 10px;\"><a class=\"mkdf-btn mkdf-btn-medium mkdf-btn-outline\" style=\"color: #43d5cb; padding: 14px 30px; border: 1px solid #43d5cb; border-radius: 5px; font-weight: 300;\" href=\"https:\/\/altos-klinika.cz\/de\/ultrasound-liposuction-on-triactive\/\" target=\"_self\" rel=\"noopener\">Mehr Info<\/a><\/p>\n<p>[\/vc_column_text]\t\t<\/p><\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_empty_space height=\"50px\"][\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"mkdf-elements-holder mkdf-three-columns mkdf-responsive-mode-1024\"><div class=\"mkdf-eh-item \" data-item-class=\"mkdf-eh-custom-497611\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-497611\">\n\t\t\t<div class=\"mkdf-interactive-banner-holder mkdf-interactive-banner-align-center mkdf-interactive-banner-light-theme mkdf-interactive-banner-standard\" style=\"padding: 15%\"><a itemprop=\"url\" class=\"mkdf-interactive-banner-cover-link\" href=\"\/de\/laser-rejuvenation\/\" target=\"_self\"><\/a><div class=\"mkdf-interactive-banner-initial\" style=\"background-color: #435BA1\"><\/div><div class=\"mkdf-interactive-banner-overlay\" style=\"background-color: #546AA9\"><\/div><div class=\"mkdf-interactive-banner-inner-wrapper\">\n    <div class=\"mkdf-interactive-banner-content-holder\">\n                    <div class=\"mkdf-interactive-banner-title-holder\">\n                <h3>\n                    Laserverj\u00fcngung                <\/h3>\n            <\/div>\n                        <div class=\"mkdf-interactive-banner-text-holder\">\n            <p>Jede Haut braucht einen individuellen Ansatz \u2013 die Laserverj\u00fcngung hat einen signifikanten und langanhaltenden Effekt, der zu einer allgemeinen Verbesserung der Hautqualit\u00e4t (Elastizit\u00e4t, Struktur, Spannkraft) f\u00fchrt.<\/p>\n                                            <a itemprop=\"url\" href=\"\/de\/laser-rejuvenation\/\" target=\"_self\" class=\"mkdf-btn mkdf-btn-medium mkdf-btn-solid mkdf-btn-solid-light mkdf-btn-icon\">    <span class=\"mkdf-btn-text\">Mehr Info<\/span>    <span class=\"mkdf-btn-icon-holder\">        <span class=\"mkdf-btn-icon-normal\"><i class=\"mkdf-icon-ion-icon ion-chevron-right \"><\/i><\/span>        <span class=\"mkdf-btn-icon-flip\"><i class=\"mkdf-icon-ion-icon ion-chevron-right \"><\/i><\/span>    <\/span><\/a>                    <\/div>\n    <\/div>\n<\/div><\/div>\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"mkdf-eh-item \" data-item-class=\"mkdf-eh-custom-308580\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-308580\">\n\t\t\t<div class=\"mkdf-interactive-banner-holder mkdf-interactive-banner-align-center mkdf-interactive-banner-light-theme mkdf-interactive-banner-standard\" style=\"padding: 15%\"><a itemprop=\"url\" class=\"mkdf-interactive-banner-cover-link\" href=\"\/de\/laser-removal\/\" target=\"_self\"><\/a><div class=\"mkdf-interactive-banner-initial\" style=\"background-color: #45d2ca\"><\/div><div class=\"mkdf-interactive-banner-overlay\" style=\"background-color: #6adcd6\"><\/div><div class=\"mkdf-interactive-banner-inner-wrapper\">\n    <div class=\"mkdf-interactive-banner-content-holder\">\n                    <div class=\"mkdf-interactive-banner-title-holder\">\n                <h3>\n                    Laserentfernung                <\/h3>\n            <\/div>\n                        <div class=\"mkdf-interactive-banner-text-holder\">\n            <p>Dank der Multifunktionalit\u00e4t unseres Ger\u00e4tes bieten wir die Entfernung jeglicher Art von Hautwucherungen, Pigmentflecken, erweiterten \u00c4derchen, Narben und T\u00e4towierungen an<\/p>\n                                            <a itemprop=\"url\" href=\"\/de\/laser-removal\/\" target=\"_self\" class=\"mkdf-btn mkdf-btn-medium mkdf-btn-solid mkdf-btn-solid-light mkdf-btn-icon\">    <span class=\"mkdf-btn-text\">Mehr Info<\/span>    <span class=\"mkdf-btn-icon-holder\">        <span class=\"mkdf-btn-icon-normal\"><i class=\"mkdf-icon-ion-icon ion-chevron-right \"><\/i><\/span>        <span class=\"mkdf-btn-icon-flip\"><i class=\"mkdf-icon-ion-icon ion-chevron-right \"><\/i><\/span>    <\/span><\/a>                    <\/div>\n    <\/div>\n<\/div><\/div>\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"mkdf-eh-item \" data-item-class=\"mkdf-eh-custom-679805\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-679805\">\n\t\t\t<div class=\"mkdf-interactive-banner-holder mkdf-interactive-banner-align-center mkdf-interactive-banner-light-theme mkdf-interactive-banner-standard\" style=\"padding: 15%\"><a itemprop=\"url\" class=\"mkdf-interactive-banner-cover-link\" href=\"\/de\/injection-methods\/\" target=\"_self\"><\/a><div class=\"mkdf-interactive-banner-initial\" style=\"background-color: #516DC5\"><\/div><div class=\"mkdf-interactive-banner-overlay\" style=\"background-color: #546AA9\"><\/div><div class=\"mkdf-interactive-banner-inner-wrapper\">\n    <div class=\"mkdf-interactive-banner-content-holder\">\n                    <div class=\"mkdf-interactive-banner-title-holder\">\n                <h3>\n                    Injektionsmethoden                <\/h3>\n            <\/div>\n                        <div class=\"mkdf-interactive-banner-text-holder\">\n            <p>Wir verlangsamen Ihre Hautalterung und regenerieren Ihre Haut mit <a href=\"https:\/\/altos-klinika.cz\/de\/injection-methods\/\" title=\"Injektionsmethoden\" class=\"text-link\">Injektionsmethoden<\/a>. W\u00e4hlen Sie das Richtige oder lassen Sie sich von unserem Arzt beraten, der f\u00fcr Sie geeignet ist.<\/p>\n                                            <a itemprop=\"url\" href=\"\/de\/injection-methods\/\" target=\"_self\" class=\"mkdf-btn mkdf-btn-medium mkdf-btn-solid mkdf-btn-solid-light mkdf-btn-icon\">    <span class=\"mkdf-btn-text\">Mehr Info<\/span>    <span class=\"mkdf-btn-icon-holder\">        <span class=\"mkdf-btn-icon-normal\"><i class=\"mkdf-icon-ion-icon ion-chevron-right \"><\/i><\/span>        <span class=\"mkdf-btn-icon-flip\"><i class=\"mkdf-icon-ion-icon ion-chevron-right \"><\/i><\/span>    <\/span><\/a>                    <\/div>\n    <\/div>\n<\/div><\/div>\t\t<\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"mkdf-elements-holder mkdf-one-column mkdf-responsive-mode-768\"><div class=\"mkdf-eh-item mkdf-horizontal-alignment-center\" data-item-class=\"mkdf-eh-custom-243052\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-243052\" style=\"padding: 100px 0px 0px 0px\">\n\t\t\t<div class=\"mkdf-section-title-holder mkdf-st-standard mkdf-st-title-left mkdf-st-normal-space \">\n\t<div class=\"mkdf-st-inner\">\n\t\t\t\t\t<h2 class=\"mkdf-st-title\">\n\t\t\t\tLaserentfernung von Hautl\u00e4sionen\t\t\t<\/h2>\n\t\t\t\t\t<\/div>\n<\/div>[vc_column_text]\n<p style=\"text-align: center;\">Dank der Multifunktionalit\u00e4t unserer Ger\u00e4te bieten wir die Entfernung jeglicher Art von Hautwucherungen und Pigmentierungen an.<\/p>\n<p>[\/vc_column_text]\t\t<\/p><\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column][\/vc_row][vc_row][vc_column][vc_row_inner][vc_column_inner width=\"1\/3\" css=\".vc_custom_1683032119027{border-right-width: 1px !important;border-left-width: 1px !important;padding-top: 0% !important;padding-right: 0% !important;padding-bottom: 0% !important;padding-left: 0% !important;border-left-color: #ededed !important;border-left-style: solid !important;border-right-color: #ededed !important;border-right-style: solid !important;}\" offset=\"vc_col-xs-12\"]<div class=\"mkdf-elements-holder mkdf-one-column mkdf-responsive-mode-768\"><div class=\"mkdf-eh-item mkdf-horizontal-alignment-center\" data-item-class=\"mkdf-eh-custom-853913\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-853913\" style=\"padding: 55px 10%\">\n\t\t\t[vc_column_text]\n<h3>Entfernung von Laserwachstum<\/h3>\n<p>Entfernung von Wucherungen (unpigmentierte N\u00e4vi) mit einem modernen SmartXide2 CO2-Laser. Die Wirkung des Lasers besteht darin, die einzelnen Hautschichten nach und nach zu verdampfen. Der Laser richtet einen Lichtstrahl aus, der nur auf das Lager trifft, das wir entfernen m\u00f6chten.[\/vc_column_text][vc_empty_space][vc_column_text css=\"\"]<\/p>\n<p style=\"text-align: center; margin-top: 10px;\"><a class=\"mkdf-btn mkdf-btn-medium mkdf-btn-outline\" style=\"color: #43d5cb; padding: 14px 30px; border: 1px solid #43d5cb; border-radius: 5px; font-weight: 300;\" href=\"https:\/\/altos-klinika.cz\/de\/laser-growths-removal\/\" target=\"_self\" rel=\"noopener\">Mehr Info<\/a><\/p>\n<p>[\/vc_column_text]\t\t<\/p><\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column_inner][vc_column_inner width=\"1\/3\" css=\".vc_custom_1683032128418{border-right-width: 1px !important;border-left-width: 1px !important;padding-top: 0% !important;padding-right: 0% !important;padding-bottom: 0% !important;padding-left: 0% !important;border-left-color: #ededed !important;border-left-style: solid !important;border-right-color: #ededed !important;border-right-style: solid !important;}\" offset=\"vc_col-xs-12\"]<div class=\"mkdf-elements-holder mkdf-one-column mkdf-responsive-mode-768\"><div class=\"mkdf-eh-item mkdf-horizontal-alignment-center\" data-item-class=\"mkdf-eh-custom-891566\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-891566\" style=\"padding: 55px 10%\">\n\t\t\t[vc_column_text]\n<h3>Laserentfernung von Warzen<\/h3>\n<p>Plantarwarzen werden haupts\u00e4chlich aus \u00e4sthetischen Gr\u00fcnden entfernt. Es bildet sich an jedem Teil des K\u00f6rpers, was unangenehm, aber nicht gef\u00e4hrlich sein kann. Ihr Nachteil ist, dass sie sich vermehren k\u00f6nnen und dann schwerer wieder loszuwerden sind. Die einfachste L\u00f6sung ist die Laserbehandlung, die eine effektive und f\u00fcr viele Patienten die einfachste Form der Entfernung darstellt.[\/vc_column_text][vc_empty_space][vc_column_text css=\"\"]<\/p>\n<p style=\"text-align: center; margin-top: 10px;\"><a class=\"mkdf-btn mkdf-btn-medium mkdf-btn-outline\" style=\"color: #43d5cb; padding: 14px 30px; border: 1px solid #43d5cb; border-radius: 5px; font-weight: 300;\" href=\"https:\/\/altos-klinika.cz\/de\/laser-removal-of-warts\/\" target=\"_self\" rel=\"noopener\">Mehr Info<\/a><\/p>\n<p>[\/vc_column_text]\t\t<\/p><\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column_inner][vc_column_inner width=\"1\/3\" css=\".vc_custom_1683032138490{padding-top: 0% !important;padding-right: 0% !important;padding-bottom: 0% !important;padding-left: 0% !important;}\" offset=\"vc_col-xs-12\"]<div class=\"mkdf-elements-holder mkdf-one-column mkdf-responsive-mode-768\"><div class=\"mkdf-eh-item mkdf-horizontal-alignment-center\" data-item-class=\"mkdf-eh-custom-702700\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-702700\" style=\"padding: 55px 10%\">\n\t\t\t[vc_column_text]\n<h3>Laserh\u00e4mangiomentfernung<\/h3>\n<p>Das H\u00e4mangiom ist ein angeborener gutartiger Tumor des Gef\u00e4\u00dfgewebes. Die Laserenergie durchdringt die Haut und wird vorzugsweise vom H\u00e4moglobin in den Gef\u00e4\u00dfen innerhalb der Gef\u00e4\u00dfl\u00e4sion oder des H\u00e4mangioms absorbiert. Die Hitze des Lasers zerst\u00f6rt die Blutgef\u00e4\u00dfe, ohne das umliegende Gewebe zu sch\u00e4digen.[\/vc_column_text][vc_empty_space][vc_column_text css=\"\"]<\/p>\n<p style=\"text-align: center; margin-top: 10px;\"><a class=\"mkdf-btn mkdf-btn-medium mkdf-btn-outline\" style=\"color: #43d5cb; padding: 14px 30px; border: 1px solid #43d5cb; border-radius: 5px; font-weight: 300;\" href=\"https:\/\/altos-klinika.cz\/de\/laser-hemangioma-removal\/\" target=\"_self\" rel=\"noopener\">Mehr Info<\/a><\/p>\n<p>[\/vc_column_text]\t\t<\/p><\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=\"1\/3\" css=\".vc_custom_1683032160178{border-right-width: 1px !important;border-bottom-width: 0px !important;border-left-width: 1px !important;padding-top: 0% !important;padding-right: 0% !important;padding-bottom: 0% !important;padding-left: 0% !important;border-left-color: #ededed !important;border-left-style: solid !important;border-right-color: #ededed !important;border-right-style: solid !important;border-bottom-color: #ededed !important;border-bottom-style: solid !important;}\" offset=\"vc_col-xs-12\"]<div class=\"mkdf-elements-holder mkdf-one-column mkdf-responsive-mode-768\"><div class=\"mkdf-eh-item mkdf-horizontal-alignment-center\" data-item-class=\"mkdf-eh-custom-225917\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-225917\" style=\"padding: 55px 10%\">\n\t\t\t[vc_column_text]\n<h3>Laserentfernung von Muttermalen<\/h3>\n<p>Vor jeder Entfernung von Muttermalen ist es immer notwendig, das Mal mit einem Dermatoskop zu untersuchen, um eine verd\u00e4chtige Einheit auszuschlie\u00dfen, die zur Histologie geschickt wird. Die Entfernung der Markierung selbst erfolgt mit einem geeigneten Laser, dessen pr\u00e4zise gerichteter Strahl das Pigment der Markierung in kleine Partikel zerbricht, die dann auf nat\u00fcrliche Weise vom K\u00f6rper weggesp\u00fclt werden.[\/vc_column_text][vc_empty_space][vc_column_text css=\"\"]<\/p>\n<p style=\"text-align: center; margin-top: 10px;\"><a class=\"mkdf-btn mkdf-btn-medium mkdf-btn-outline\" style=\"color: #43d5cb; padding: 14px 30px; border: 1px solid #43d5cb; border-radius: 5px; font-weight: 300;\" href=\"https:\/\/altos-klinika.cz\/de\/laser-removal-of-birthmarks\/\" target=\"_self\" rel=\"noopener\">Mehr Info<\/a><\/p>\n<p>[\/vc_column_text]\t\t<\/p><\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column_inner][vc_column_inner width=\"1\/3\" css=\".vc_custom_1683032170306{border-bottom-width: 0px !important;padding-top: 0% !important;padding-right: 0% !important;padding-bottom: 0% !important;padding-left: 0% !important;border-bottom-color: #ededed !important;border-bottom-style: solid !important;}\" offset=\"vc_col-xs-12\"]<div class=\"mkdf-elements-holder mkdf-one-column mkdf-responsive-mode-768\"><div class=\"mkdf-eh-item mkdf-horizontal-alignment-center\" data-item-class=\"mkdf-eh-custom-239245\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-239245\" style=\"padding: 55px 10%\">\n\t\t\t[vc_column_text]\n<h3>Laserentfernung (Korrektur) von Narben und Dehnungsstreifen<\/h3>\n<p>Die Laser-Narbenentfernung ist eine moderne, sichere Methode, die Narben, einschlie\u00dflich Keloide und Dehnungsstreifen unterschiedlichen Alters, reduziert. Das Aussehen der Narbe wird nicht nur von ihrer Lage, sondern auch von ihrem Alter beeinflusst, wobei genetische Veranlagungen eine wichtige Rolle spielen. Modernste Laser k\u00f6nnen entstehende Unebenheiten ausgleichen und die Kollagenneubildung unter der Narbe unterst\u00fctzen. Dies f\u00fchrt zu seiner Abrechnung und R\u00fccknahme.[\/vc_column_text][vc_empty_space][vc_column_text css=\"\"]<\/p>\n<p style=\"text-align: center; margin-top: 10px;\"><a class=\"mkdf-btn mkdf-btn-medium mkdf-btn-outline\" style=\"color: #43d5cb; padding: 14px 30px; border: 1px solid #43d5cb; border-radius: 5px; font-weight: 300;\" href=\"https:\/\/altos-klinika.cz\/de\/laser-scar-correction\/\" target=\"_self\" rel=\"noopener\">Mehr Info<\/a><\/p>\n<p>[\/vc_column_text]\t\t<\/p><\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column_inner][vc_column_inner width=\"1\/3\" css=\".vc_custom_1683032180617{border-bottom-width: 0px !important;padding-top: 0% !important;padding-right: 0% !important;padding-bottom: 0% !important;padding-left: 0% !important;border-bottom-color: #ededed !important;border-bottom-style: solid !important;}\" offset=\"vc_col-xs-12\"]<div class=\"mkdf-elements-holder mkdf-one-column mkdf-responsive-mode-768\"><div class=\"mkdf-eh-item mkdf-horizontal-alignment-center\" data-item-class=\"mkdf-eh-custom-464103\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-464103\" style=\"padding: 55px 10%\">\n\t\t\t[vc_column_text]\n<h3>Laserentfernung von Krampfadern<\/h3>\n<p>Ausgedehnte Venen oder Besenreiser sind ein un\u00e4sthetisches Problem, bei dem wir einen Gef\u00e4\u00dflaser verwenden, um mit Hilfe eines richtig gerichteten Strahls und hoher Temperatur eine Koagulation (Kontraktion) zu verursachen. Er stirbt allm\u00e4hlich und wird absorbiert.[\/vc_column_text][vc_empty_space][vc_column_text css=\"\"]<\/p>\n<p style=\"text-align: center; margin-top: 10px;\"><a class=\"mkdf-btn mkdf-btn-medium mkdf-btn-outline\" style=\"color: #43d5cb; padding: 14px 30px; border: 1px solid #43d5cb; border-radius: 5px; font-weight: 300;\" href=\"https:\/\/altos-klinika.cz\/de\/laser-removal-of-varicose-veins\/\" target=\"_self\" rel=\"noopener\">Mehr Info<\/a><\/p>\n<p>[\/vc_column_text]\t\t<\/p><\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row row_content_width=\"grid\"][vc_column]<div class=\"mkdf-elements-holder mkdf-one-column mkdf-responsive-mode-768\"><div class=\"mkdf-eh-item mkdf-horizontal-alignment-center\" data-item-class=\"mkdf-eh-custom-834726\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-834726\" style=\"padding: 100px 0px 50px 0px\">\n\t\t\t<div class=\"mkdf-section-title-holder mkdf-st-standard mkdf-st-title-left mkdf-st-normal-space \">\n\t<div class=\"mkdf-st-inner\">\n\t\t\t\t\t<h2 class=\"mkdf-st-title\">\n\t\t\t\t<span class=\"mkdf-st-title-bold\">Behandlung<\/span> problematischer Haut\t\t\t<\/h2>\n\t\t\t\t\t<\/div>\n<\/div>[vc_column_text]\n<p style=\"text-align: center;\">Bis zu 80 % der Bev\u00f6lkerung leiden an problematischer oder zu Akne neigender Haut. In vielen F\u00e4llen kann eine angemessene Behandlung und eine erfolgreiche Behandlung gefunden werden.<\/p>\n<p>Probleme treten h\u00e4ufig in der Pubert\u00e4t auf, wenn bei jungen Menschen gro\u00dfe hormonelle Umstellungen auftreten, vermehrt Talg gebildet wird und Porenverstopfungen, Pickel und Zysten entstehen k\u00f6nnen, die zu entz\u00fcndlichen Prozessen auf der Haut f\u00fchren k\u00f6nnen. Obwohl die Probleme haupts\u00e4chlich bei Jugendlichen auftreten, k\u00f6nnen sie auch Erwachsene betreffen, meist Frauen w\u00e4hrend der Schwangerschaft, Menstruation, Hormonumstellung usw. Es ist immer notwendig, den Zustand durch einen Dermatologen zu beurteilen, da ein schwerwiegenderes Problem mit dessen Hilfe nicht gel\u00f6st werden kann von rezeptfreier Kosmetik. Bereiche, die f\u00fcr diese Probleme anf\u00e4llig sind, sind haupts\u00e4chlich Gesicht, Schultern, R\u00fccken.<\/p>\n<p>[\/vc_column_text]\t\t<\/p><\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column][\/vc_row][vc_row][vc_column][vc_row_inner][vc_column_inner css=\".vc_custom_1633299478622{border-bottom-width: 0px !important;padding-top: 0% !important;padding-right: 0% !important;padding-bottom: 0% !important;padding-left: 0% !important;border-bottom-color: #ededed !important;border-bottom-style: solid !important;}\" offset=\"vc_col-lg-3 vc_col-md-6 vc_col-xs-12\"]<div class=\"mkdf-elements-holder mkdf-one-column mkdf-responsive-mode-768\"><div class=\"mkdf-eh-item mkdf-horizontal-alignment-center\" data-item-class=\"mkdf-eh-custom-822968\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-822968\" style=\"padding: 55px 10%\">\n\t\t\t[vc_column_text]\n<h3>Akne- und Post-Akne-Behandlung<\/h3>\n<p>Pigmentflecken oder \u00fcberm\u00e4\u00dfige Hautpigmentbildung in der Haut plagen eine Vielzahl von Patienten. Es gibt mehrere Gr\u00fcnde, wie hormonelle Einfl\u00fcsse, \u00fcberm\u00e4\u00dfige UV-Strahlung, Solarien, Hautalterung.<br>\nZur Behandlung k\u00f6nnen intensives gepulstes Licht, CO2-Laser oder <a href=\"https:\/\/altos-klinika.cz\/de\/chemical-peel\/\" title=\"chemisches Peeling\" class=\"text-link\">chemisches Peeling<\/a> eingesetzt werden.[\/vc_column_text][vc_empty_space][vc_column_text css=\"\"]<\/p>\n<p style=\"text-align: center; margin-top: 10px;\"><a class=\"mkdf-btn mkdf-btn-medium mkdf-btn-outline\" style=\"color: #43d5cb; padding: 14px 30px; border: 1px solid #43d5cb; border-radius: 5px; font-weight: 300;\" href=\"https:\/\/altos-klinika.cz\/de\/acne-treatment\/\" target=\"_self\" rel=\"noopener\">Mehr Info<\/a><\/p>\n<p>[\/vc_column_text]\t\t<\/p><\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"mkdf-elements-holder mkdf-one-column mkdf-responsive-mode-768\"><div class=\"mkdf-eh-item mkdf-horizontal-alignment-center\" data-item-class=\"mkdf-eh-custom-203571\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-203571\" style=\"padding: 100px 0px 0px 0px\">\n\t\t\t<div class=\"mkdf-section-title-holder mkdf-st-standard mkdf-st-title-left mkdf-st-normal-space \">\n\t<div class=\"mkdf-st-inner\">\n\t\t\t\t\t<h2 class=\"mkdf-st-title\">\n\t\t\t\t<span class=\"mkdf-st-title-bold\">Laserverj\u00fcngung<\/span>\t\t\t<\/h2>\n\t\t\t\t\t<\/div>\n<\/div>[vc_column_text]\n<p style=\"text-align: center;\">H\u00e4ngende Konturen und Falten sind oft die Folge von Kollagenverlust. Narben, Pigmentflecken, vergr\u00f6\u00dferte Poren machen unser Leben unangenehm und mindern unser Selbstbewusstsein.<\/p>\n<p>Deshalb kommen wir zur richtigen Zeit und bieten Laserverj\u00fcngungsmethoden an, die der Haut helfen, sich zu regenerieren, die Elastizit\u00e4t zu verbessern, zu gl\u00e4tten und aufzuhellen.<\/p>\n<p>[\/vc_column_text]\t\t<\/p><\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column][\/vc_row][vc_row css=\".vc_custom_1633293452436{padding-top: 45px !important;padding-bottom: 25px !important;}\"][vc_column][vc_row_inner][vc_column_inner css=\".vc_custom_1633299472059{border-right-width: 1px !important;border-bottom-width: 0px !important;border-left-width: 1px !important;padding-top: 0% !important;padding-right: 0% !important;padding-bottom: 0% !important;padding-left: 0% !important;border-left-color: #ededed !important;border-left-style: solid !important;border-right-color: #ededed !important;border-right-style: solid !important;border-bottom-color: #ededed !important;border-bottom-style: solid !important;}\" offset=\"vc_col-lg-3 vc_col-md-6 vc_col-xs-12\"]<div class=\"mkdf-elements-holder mkdf-one-column mkdf-responsive-mode-768\"><div class=\"mkdf-eh-item mkdf-horizontal-alignment-center\" data-item-class=\"mkdf-eh-custom-174384\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-174384\" style=\"padding: 55px 10%\">\n\t\t\t[vc_column_text]\n<h3>Fractional Laser Resurfacing<\/h3>\n<p>Fractional Resurfacing ist eine ideale Wahl f\u00fcr alternde oder gesch\u00e4digte Haut. Es wirkt auf die Oberfl\u00e4che der oberen Schicht, stimuliert gleichzeitig das Wachstum neuer Hautzellen und die Bildung von neuem Kollagen und startet so den nat\u00fcrlichen Heilungsprozess.[\/vc_column_text][vc_empty_space][vc_column_text css=\"\"]<\/p>\n<p style=\"text-align: center; margin-top: 10px;\"><a class=\"mkdf-btn mkdf-btn-medium mkdf-btn-outline\" style=\"color: #43d5cb; padding: 14px 30px; border: 1px solid #43d5cb; border-radius: 5px; font-weight: 300;\" href=\"https:\/\/altos-klinika.cz\/de\/laser-resurfacing\/\" target=\"_self\" rel=\"noopener\">Mehr Info<\/a><\/p>\n<p>[\/vc_column_text]\t\t<\/p><\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column_inner][vc_column_inner css=\".vc_custom_1633299478622{border-bottom-width: 0px !important;padding-top: 0% !important;padding-right: 0% !important;padding-bottom: 0% !important;padding-left: 0% !important;border-bottom-color: #ededed !important;border-bottom-style: solid !important;}\" offset=\"vc_col-lg-3 vc_col-md-6 vc_col-xs-12\"]<div class=\"mkdf-elements-holder mkdf-one-column mkdf-responsive-mode-768\"><div class=\"mkdf-eh-item mkdf-horizontal-alignment-center\" data-item-class=\"mkdf-eh-custom-219429\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-219429\" style=\"padding: 55px 10%\">\n\t\t\t[vc_column_text]\n<h3>Laserverj\u00fcngung ND: Yag<\/h3>\n<p>Der Laser wirkt in den tieferen Hautschichten, unterst\u00fctzt die Kollagenbildung und gl\u00e4ttet die Haut. Die Laserverj\u00fcngung hat einen signifikanten und lang anhaltenden Effekt, der zu einer allgemeinen Verbesserung der Hautqualit\u00e4t f\u00fchrt.[\/vc_column_text][vc_empty_space][vc_column_text css=\"\"]<\/p>\n<p style=\"text-align: center; margin-top: 10px;\"><a class=\"mkdf-btn mkdf-btn-medium mkdf-btn-outline\" style=\"color: #43d5cb; padding: 14px 30px; border: 1px solid #43d5cb; border-radius: 5px; font-weight: 300;\" href=\"https:\/\/altos-klinika.cz\/de\/rejuvenation-with-nd-yag-laser\/\" target=\"_self\" rel=\"noopener\">Mehr Info<\/a><\/p>\n<p>[\/vc_column_text]\t\t<\/p><\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column_inner][vc_column_inner css=\".vc_custom_1633299485278{border-right-width: 1px !important;border-bottom-width: 0px !important;border-left-width: 1px !important;padding-top: 0% !important;padding-right: 0% !important;padding-bottom: 0% !important;padding-left: 0% !important;border-left-color: #ededed !important;border-left-style: solid !important;border-right-color: #ededed !important;border-right-style: solid !important;border-bottom-color: #ededed !important;border-bottom-style: solid !important;}\" offset=\"vc_col-lg-3 vc_col-md-6 vc_col-xs-12\"]<div class=\"mkdf-elements-holder mkdf-one-column mkdf-responsive-mode-768\"><div class=\"mkdf-eh-item mkdf-horizontal-alignment-center\" data-item-class=\"mkdf-eh-custom-965916\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-965916\" style=\"padding: 55px 10%\">\n\t\t\t[vc_column_text]\n<h3>Radiofrequenz-Lifting<\/h3>\n<p>Rf-Gesichtslifting mit dem TriActive + -Ger\u00e4t ist eine nicht-chirurgische Methode zur Straffung der Gesichtshaut. Ein wichtiger Faktor beim Radiofrequenz-Lifting ist das schmerzfreie Herunterfahren der Haut, die Reduzierung von feinen Linien und F\u00e4ltchen und die Konturierung des Gesichts.[\/vc_column_text][vc_empty_space][vc_column_text css=\"\"]<\/p>\n<p style=\"text-align: center; margin-top: 10px;\"><a class=\"mkdf-btn mkdf-btn-medium mkdf-btn-outline\" style=\"color: #43d5cb; padding: 14px 30px; border: 1px solid #43d5cb; border-radius: 5px; font-weight: 300;\" href=\"https:\/\/altos-klinika.cz\/de\/rf-facelifting\/\" target=\"_self\" rel=\"noopener\">Mehr Info<\/a><\/p>\n<p>[\/vc_column_text]\t\t<\/p><\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column_inner][vc_column_inner css=\".vc_custom_1633299493433{border-bottom-width: 0px !important;padding-top: 0% !important;padding-right: 0% !important;padding-bottom: 0% !important;padding-left: 0% !important;border-bottom-color: #ededed !important;border-bottom-style: solid !important;}\" offset=\"vc_col-lg-3 vc_col-md-6 vc_col-xs-12\"]<div class=\"mkdf-elements-holder mkdf-one-column mkdf-responsive-mode-768\"><div class=\"mkdf-eh-item mkdf-horizontal-alignment-center\" data-item-class=\"mkdf-eh-custom-175623\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-175623\" style=\"padding: 55px 10%\">\n\t\t\t[vc_column_text]\n<h3>Ultraschall-SMAS-Lifting<\/h3>\n<p>Die verj\u00fcngende, nicht-chirurgische Methode bek\u00e4mpft effektiv alternde, schlaffe Haut und Falten ohne die notwendige und langwierige Rekonvaleszenz. Ultraschall wirkt auf die muskelaponeurotische Schicht der Haut, SMAS genannt, die sich unter den Fettzellen in der Haut befindet. Die nicht-invasive Methode dringt sowohl unter die Haut als auch unter die Muskulatur und unterst\u00fctzt dort die Produktion von Kollagen und Elastin.[\/vc_column_text][vc_empty_space][vc_column_text css=\"\"]<\/p>\n<p style=\"text-align: center; margin-top: 10px;\"><a class=\"mkdf-btn mkdf-btn-medium mkdf-btn-outline\" style=\"color: #43d5cb; padding: 14px 30px; border: 1px solid #43d5cb; border-radius: 5px; font-weight: 300;\" href=\"https:\/\/altos-klinika.cz\/de\/ulthera-lifting\/\" target=\"_self\" rel=\"noopener\">Mehr Info<\/a><\/p>\n<p>[\/vc_column_text]\t\t<\/p><\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"mkdf-elements-holder mkdf-one-column mkdf-responsive-mode-768\"><div class=\"mkdf-eh-item mkdf-horizontal-alignment-center\" data-item-class=\"mkdf-eh-custom-747030\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-747030\" style=\"padding: 100px 0px 0px 0px\">\n\t\t\t<div class=\"mkdf-section-title-holder mkdf-st-standard mkdf-st-title-left mkdf-st-normal-space \">\n\t<div class=\"mkdf-st-inner\">\n\t\t\t\t\t<h2 class=\"mkdf-st-title\">\n\t\t\t\t<span class=\"mkdf-st-title-bold\">Verj\u00fcngungsinjektionsmethoden<\/span> <span class=\"mkdf-st-title-bold\"><\/span>\t\t\t<\/h2>\n\t\t\t\t\t<\/div>\n<\/div>[vc_column_text]\n<p style=\"text-align: center;\">Wir verlangsamen Ihre Hautalterung und regenerieren Ihre Haut mit Injektionsmethoden.<br>\nW\u00e4hlen Sie das Richtige oder lassen Sie sich von unseren \u00c4rzte beraten, die f\u00fcr Sie geeignet sind.<\/p>\n<p>[\/vc_column_text]\t\t<\/p><\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column][\/vc_row][vc_row css=\".vc_custom_1633293452436{padding-top: 45px !important;padding-bottom: 25px !important;}\"][vc_column][vc_row_inner equal_height=\"yes\"][vc_column_inner css=\".vc_custom_1633299472059{border-right-width: 1px !important;border-bottom-width: 0px !important;border-left-width: 1px !important;padding-top: 0% !important;padding-right: 0% !important;padding-bottom: 0% !important;padding-left: 0% !important;border-left-color: #ededed !important;border-left-style: solid !important;border-right-color: #ededed !important;border-right-style: solid !important;border-bottom-color: #ededed !important;border-bottom-style: solid !important;}\" offset=\"vc_col-lg-3 vc_col-md-6 vc_col-xs-12\"]<div class=\"mkdf-elements-holder mkdf-one-column mkdf-responsive-mode-768\"><div class=\"mkdf-eh-item mkdf-horizontal-alignment-center\" data-item-class=\"mkdf-eh-custom-529520\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-529520\" style=\"padding: 55px 10%\">\n\t\t\t[vc_column_text]\n<h3>Biorevitalisierung<\/h3>\n<p>Bei der Biotevitalisierung wird Hyalurons\u00e4ure mit einer h\u00f6heren Konzentration verwendet. Diese nat\u00fcrliche Hauttherapie tr\u00e4gt dazu bei, eine optimale Hautfeuchtigkeit zu gew\u00e4hrleisten und ihre gesunde Farbe, Elastizit\u00e4t und Spannkraft wiederherzustellen. Es hilft nicht nur, das Erscheinungsbild von Falten zu reduzieren, sondern liefert auch N\u00e4hrstoffbausteine, die die nat\u00fcrliche F\u00e4higkeit der Haut zur Verj\u00fcngung stimulieren.[\/vc_column_text][vc_empty_space][vc_column_text css=\"\"]<\/p>\n<p style=\"text-align: center; margin-top: 10px;\"><a class=\"mkdf-btn mkdf-btn-medium mkdf-btn-outline\" style=\"color: #43d5cb; padding: 14px 30px; border: 1px solid #43d5cb; border-radius: 5px; font-weight: 300;\" href=\"https:\/\/altos-klinika.cz\/de\/biorevitalization\/\" target=\"_self\" rel=\"noopener\">Mehr Info<\/a><\/p>\n<p>[\/vc_column_text]\t\t<\/p><\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column_inner][vc_column_inner css=\".vc_custom_1633299478622{border-bottom-width: 0px !important;padding-top: 0% !important;padding-right: 0% !important;padding-bottom: 0% !important;padding-left: 0% !important;border-bottom-color: #ededed !important;border-bottom-style: solid !important;}\" offset=\"vc_col-lg-3 vc_col-md-6 vc_col-xs-12\"]<div class=\"mkdf-elements-holder mkdf-one-column mkdf-responsive-mode-768\"><div class=\"mkdf-eh-item mkdf-horizontal-alignment-center\" data-item-class=\"mkdf-eh-custom-250629\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-250629\" style=\"padding: 55px 10%\">\n\t\t\t[vc_column_text]\n<h3>Mesotherapie<\/h3>\n<p>Urspr\u00fcnglich aus Frankreich, eine Anti-Age-Methode zur Verbesserung und Hydratisierung der Haut durch Anwendung von nahrhaften Cocktails, Vitaminen, Enzymen, Antioxidantien und Pflanzenextrakten. Mesotherapeutische Vitamincocktails regen die Fibroblastenzellen an, mehr Kollagen zu produzieren und die Zeichen der Hautalterung zu bek\u00e4mpfen.[\/vc_column_text][vc_empty_space][vc_column_text css=\"\"]<\/p>\n<p style=\"text-align: center; margin-top: 10px;\"><a class=\"mkdf-btn mkdf-btn-medium mkdf-btn-outline\" style=\"color: #43d5cb; padding: 14px 30px; border: 1px solid #43d5cb; border-radius: 5px; font-weight: 300;\" href=\"https:\/\/altos-klinika.cz\/de\/mesotherapy\/\" target=\"_self\" rel=\"noopener\">Mehr Info<\/a><\/p>\n<p>[\/vc_column_text]\t\t<\/p><\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column_inner][vc_column_inner css=\".vc_custom_1633299485278{border-right-width: 1px !important;border-bottom-width: 0px !important;border-left-width: 1px !important;padding-top: 0% !important;padding-right: 0% !important;padding-bottom: 0% !important;padding-left: 0% !important;border-left-color: #ededed !important;border-left-style: solid !important;border-right-color: #ededed !important;border-right-style: solid !important;border-bottom-color: #ededed !important;border-bottom-style: solid !important;}\" offset=\"vc_col-lg-3 vc_col-md-6 vc_col-xs-12\"]<div class=\"mkdf-elements-holder mkdf-one-column mkdf-responsive-mode-768\"><div class=\"mkdf-eh-item mkdf-horizontal-alignment-center\" data-item-class=\"mkdf-eh-custom-747839\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-747839\" style=\"padding: 55px 10%\">\n\t\t\t[vc_column_text]\n<h3>Plasmalifting<\/h3>\n<p>Das Hauptprinzip des Plasma-Elevation-Verfahrens ist die Biostimulation von Kollagenfasern in der Haut. Die Plasmalackierung verlangsamt die Alterung und setzt die Verj\u00fcngung wieder in Gang. Die Methode verwendet Ihr eigenes Blutplasma, ein k\u00f6rpereigenes Produkt, und ist daher frei von allergischen Reaktionen.[\/vc_column_text][vc_empty_space][vc_column_text css=\"\"]<\/p>\n<p style=\"text-align: center; margin-top: 10px;\"><a class=\"mkdf-btn mkdf-btn-medium mkdf-btn-outline\" style=\"color: #43d5cb; padding: 14px 30px; border: 1px solid #43d5cb; border-radius: 5px; font-weight: 300;\" href=\"https:\/\/altos-klinika.cz\/de\/plazmolifting\/\" target=\"_self\" rel=\"noopener\">Mehr Info<\/a><\/p>\n<p>[\/vc_column_text]\t\t<\/p><\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column_inner][vc_column_inner css=\".vc_custom_1633299493433{border-bottom-width: 0px !important;padding-top: 0% !important;padding-right: 0% !important;padding-bottom: 0% !important;padding-left: 0% !important;border-bottom-color: #ededed !important;border-bottom-style: solid !important;}\" offset=\"vc_col-lg-3 vc_col-md-6 vc_col-xs-12\"]<div class=\"mkdf-elements-holder mkdf-one-column mkdf-responsive-mode-768\"><div class=\"mkdf-eh-item mkdf-horizontal-alignment-center\" data-item-class=\"mkdf-eh-custom-504880\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-504880\" style=\"padding: 55px 10%\">\n\t\t\t[vc_column_text]\n<h3>Microneedling<\/h3>\n<p><a href=\"https:\/\/altos-klinika.cz\/de\/microneedling\/\" title=\"Microneedling\" class=\"text-link\">Microneedling<\/a> oder Microneedling geh\u00f6rt zu der Methode, die bei verschiedenen Hauterkrankungen, wie der Behandlung von Akne, Narben, Dehnungsstreifen, Haarausfall, eingesetzt wird. Der Haupteffekt von Microneedling besteht darin, dass die auf die Hautoberfl\u00e4che aufgetragenen Wirkstoffe durch die Oberfl\u00e4chenschichten der Epidermis dringen k\u00f6nnen, um genau dort anzukommen, wo die Haut ein Problem hat.[\/vc_column_text][vc_empty_space][vc_column_text css=\"\"]<\/p>\n<p style=\"text-align: center; margin-top: 10px;\"><a class=\"mkdf-btn mkdf-btn-medium mkdf-btn-outline\" style=\"color: #43d5cb; padding: 14px 30px; border: 1px solid #43d5cb; border-radius: 5px; font-weight: 300;\" href=\"https:\/\/altos-klinika.cz\/de\/microneedling\/\" target=\"_self\" rel=\"noopener\">Mehr Info<\/a><\/p>\n<p>[\/vc_column_text]\t\t<\/p><\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=\"yes\"][vc_column_inner css=\".vc_custom_1633647345641{border-top-width: 1px !important;border-right-width: 1px !important;border-bottom-width: 1px !important;border-left-width: 1px !important;padding-top: 0% !important;padding-right: 0% !important;padding-bottom: 0% !important;padding-left: 0% !important;border-left-color: #ededed !important;border-left-style: solid !important;border-right-color: #ededed !important;border-right-style: solid !important;border-top-color: #ededed !important;border-top-style: solid !important;border-bottom-color: #ededed !important;border-bottom-style: solid !important;}\" offset=\"vc_col-lg-3 vc_col-md-6 vc_col-xs-12\"]<div class=\"mkdf-elements-holder mkdf-one-column mkdf-responsive-mode-768\"><div class=\"mkdf-eh-item mkdf-horizontal-alignment-center\" data-item-class=\"mkdf-eh-custom-616322\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-616322\" style=\"padding: 55px 10%\">\n\t\t\t[vc_column_text]\n<h3>Lippenvergr\u00f6\u00dferung<\/h3>\n<p>Ein volleres und sinnlicheres Aussehen der Lippen ist der Traum jeder Kundin, die mit der Form oder Asymmetrie der Lippen nicht zufrieden ist. Wir verwenden zum F\u00fcllen unserer Lippen Top-Hyalurons\u00e4ure-F\u00fcllungen, die eine Langzeitwirkung und Feuchtigkeit bieten.[\/vc_column_text][vc_empty_space][vc_column_text css=\"\"]<\/p>\n<p style=\"text-align: center; margin-top: 10px;\"><a class=\"mkdf-btn mkdf-btn-medium mkdf-btn-outline\" style=\"color: #43d5cb; padding: 14px 30px; border: 1px solid #43d5cb; border-radius: 5px; font-weight: 300;\" href=\"https:\/\/altos-klinika.cz\/de\/lips-augmentation\/\" target=\"_self\" rel=\"noopener\">Mehr Info<\/a><\/p>\n<p>[\/vc_column_text]\t\t<\/p><\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column_inner][vc_column_inner css=\".vc_custom_1638992398505{border-top-width: 1px !important;padding-top: 0% !important;padding-right: 0% !important;padding-bottom: 0% !important;padding-left: 0% !important;border-top-color: #ededed !important;border-top-style: solid !important;}\" offset=\"vc_col-lg-3 vc_col-md-6 vc_col-xs-12\"]<div class=\"mkdf-elements-holder mkdf-one-column mkdf-responsive-mode-768\"><div class=\"mkdf-eh-item mkdf-horizontal-alignment-center\" data-item-class=\"mkdf-eh-custom-468648\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-468648\" style=\"padding: 55px 10%\">\n\t\t\t[vc_column_text]\n<h3>Korrektur von Mimikfalten<\/h3>\n<p>Durch die Injektion werden die Nervenenden der Muskeln, die die Falten verursachen, f\u00fcr eine gewisse Zeit ausgeschaltet, aber es wird auch die Bildung weiterer Falten verhindert.[\/vc_column_text][vc_empty_space][vc_column_text css=\"\"]<\/p>\n<p style=\"text-align: center; margin-top: 10px;\"><a class=\"mkdf-btn mkdf-btn-medium mkdf-btn-outline\" style=\"color: #43d5cb; padding: 14px 30px; border: 1px solid #43d5cb; border-radius: 5px; font-weight: 300;\" href=\"https:\/\/altos-klinika.cz\/de\/botulinum-toxin-application\/\" target=\"_self\" rel=\"noopener\">Mehr Info<\/a><\/p>\n<p>[\/vc_column_text]\t\t<\/p><\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column_inner][vc_column_inner css=\".vc_custom_1638992408528{border-top-width: 1px !important;border-right-width: 1px !important;border-left-width: 1px !important;padding-top: 0% !important;padding-right: 0% !important;padding-bottom: 0% !important;padding-left: 0% !important;border-left-color: #ededed !important;border-left-style: solid !important;border-right-color: #ededed !important;border-right-style: solid !important;border-top-color: #ededed !important;border-top-style: solid !important;}\" offset=\"vc_col-lg-3 vc_col-md-6 vc_col-xs-12\"]<div class=\"mkdf-elements-holder mkdf-one-column mkdf-responsive-mode-768\"><div class=\"mkdf-eh-item mkdf-horizontal-alignment-center\" data-item-class=\"mkdf-eh-custom-923517\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-923517\" style=\"padding: 55px 10%\">\n\t\t\t[vc_column_text]\n<h3>F\u00fcllstoffe<\/h3>\n<p>Hautf\u00fcller auf Basis von Hyalurons\u00e4ure zielen darauf ab, Nasenlinien und Falten um die Augen zu gl\u00e4tten und Feuchtigkeit zu spenden. Sie werden haupts\u00e4chlich angewendet, um das Volumen zu erh\u00f6hen, F\u00fclle hinzuzuf\u00fcgen und Falten aufzuf\u00fcllen. Die Haut ist nach dem Auftragen des Fillers verj\u00fcngt und frisch.[\/vc_column_text][vc_empty_space][vc_column_text css=\"\"]<\/p>\n<p style=\"text-align: center; margin-top: 10px;\"><a class=\"mkdf-btn mkdf-btn-medium mkdf-btn-outline\" style=\"color: #43d5cb; padding: 14px 30px; border: 1px solid #43d5cb; border-radius: 5px; font-weight: 300;\" href=\"https:\/\/altos-klinika.cz\/de\/fillers\/\" target=\"_self\" rel=\"noopener\">Mehr Info<\/a><\/p>\n<p>[\/vc_column_text]\t\t<\/p><\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row row_content_width=\"grid\"][vc_column]<div class=\"mkdf-elements-holder mkdf-one-column mkdf-responsive-mode-768\"><div class=\"mkdf-eh-item mkdf-horizontal-alignment-center\" data-item-class=\"mkdf-eh-custom-642949\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-642949\" style=\"padding: 100px 0px 50px 0px\">\n\t\t\t<div class=\"mkdf-section-title-holder mkdf-st-standard mkdf-st-title-left mkdf-st-normal-space \">\n\t<div class=\"mkdf-st-inner\">\n\t\t\t\t\t<h2 class=\"mkdf-st-title\">\n\t\t\t\tPeelings\t\t\t<\/h2>\n\t\t\t\t\t<\/div>\n<\/div>[vc_column_text]\n<p style=\"text-align: center;\">Durch die regelm\u00e4\u00dfige Anwendung von Peelings erzielen Sie eine glatte und strahlende Haut. Alle Peelings haben ein gemeinsames Ziel, die Oberfl\u00e4chenschicht der Haut zu entfernen, was zu ihrer Erneuerung und Verj\u00fcngung f\u00fchrt. Sie sind sanfte und wirksame Produkte auf Salicyls\u00e4urebasis, die das Peeling der Haut unterst\u00fctzen und zus\u00e4tzlich Produkte enthalten, die einen erneuten Ausbruch von Entz\u00fcndungen verhindern.<\/p>\n<p>[\/vc_column_text]\t\t<\/p><\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column][\/vc_row][vc_row css=\".vc_custom_1633293452436{padding-top: 45px !important;padding-bottom: 25px !important;}\"][vc_column][vc_row_inner][vc_column_inner css=\".vc_custom_1633299472059{border-right-width: 1px !important;border-bottom-width: 0px !important;border-left-width: 1px !important;padding-top: 0% !important;padding-right: 0% !important;padding-bottom: 0% !important;padding-left: 0% !important;border-left-color: #ededed !important;border-left-style: solid !important;border-right-color: #ededed !important;border-right-style: solid !important;border-bottom-color: #ededed !important;border-bottom-style: solid !important;}\" offset=\"vc_col-lg-3 vc_col-md-6 vc_col-xs-12\"]<div class=\"mkdf-elements-holder mkdf-one-column mkdf-responsive-mode-768\"><div class=\"mkdf-eh-item mkdf-horizontal-alignment-center\" data-item-class=\"mkdf-eh-custom-989936\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-989936\" style=\"padding: 55px 10%\">\n\t\t\t[vc_column_text]\n<h3>Chemisches Peeling<\/h3>\n<p>Es ist eine schnelle Methode, um die Haut zu verj\u00fcngen und zu regenerieren. Das chemische Peeling besteht aus einer Mischung von Substanzen mit Glykols\u00e4ure (AHA-S\u00e4ure), durch deren Wirkung wir eine gereinigte Haut erhalten, die Haut kl\u00e4ren, vergr\u00f6\u00dferte Poren reduzieren, feine Falten beseitigen, den Hautton vereinheitlichen.[\/vc_column_text][vc_empty_space][vc_column_text css=\"\"]<\/p>\n<p style=\"text-align: center; margin-top: 10px;\"><a class=\"mkdf-btn mkdf-btn-medium mkdf-btn-outline\" style=\"color: #43d5cb; padding: 14px 30px; border: 1px solid #43d5cb; border-radius: 5px; font-weight: 300;\" href=\"https:\/\/altos-klinika.cz\/de\/chemical-peel\/\" target=\"_self\" rel=\"noopener\">Mehr Info<\/a><\/p>\n<p>[\/vc_column_text]\t\t<\/p><\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column_inner][vc_column_inner css=\".vc_custom_1633299478622{border-bottom-width: 0px !important;padding-top: 0% !important;padding-right: 0% !important;padding-bottom: 0% !important;padding-left: 0% !important;border-bottom-color: #ededed !important;border-bottom-style: solid !important;}\" offset=\"vc_col-lg-3 vc_col-md-6 vc_col-xs-12\"]<div class=\"mkdf-elements-holder mkdf-one-column mkdf-responsive-mode-768\"><div class=\"mkdf-eh-item mkdf-horizontal-alignment-center\" data-item-class=\"mkdf-eh-custom-978355\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-978355\" style=\"padding: 55px 10%\">\n\t\t\t[vc_column_text]\n<h3>Retinol-Peeling<\/h3>\n<p>Innovatives Retinol-Peeling wirkt als Antioxidans, reduziert das Auftreten von Falten, hilft bei der Behandlung von Akne, Reduzierung von Pigmentflecken, Narben. Der Gehalt an Vitamin A und Bisabolol tr\u00e4gt zur Regeneration, Beruhigung und Straffung der Haut bei, was zu einer gesunden und strahlenden Haut f\u00fchrt.[\/vc_column_text][vc_empty_space][vc_column_text css=\"\"]<\/p>\n<p style=\"text-align: center; margin-top: 10px;\"><a class=\"mkdf-btn mkdf-btn-medium mkdf-btn-outline\" style=\"color: #43d5cb; padding: 14px 30px; border: 1px solid #43d5cb; border-radius: 5px; font-weight: 300;\" href=\"https:\/\/altos-klinika.cz\/de\/retinol-peel\/\" target=\"_self\" rel=\"noopener\">Mehr Info<\/a><\/p>\n<p>[\/vc_column_text]\t\t<\/p><\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column_inner][vc_column_inner css=\".vc_custom_1633299485278{border-right-width: 1px !important;border-bottom-width: 0px !important;border-left-width: 1px !important;padding-top: 0% !important;padding-right: 0% !important;padding-bottom: 0% !important;padding-left: 0% !important;border-left-color: #ededed !important;border-left-style: solid !important;border-right-color: #ededed !important;border-right-style: solid !important;border-bottom-color: #ededed !important;border-bottom-style: solid !important;}\" offset=\"vc_col-lg-3 vc_col-md-6 vc_col-xs-12\"]<div class=\"mkdf-elements-holder mkdf-one-column mkdf-responsive-mode-768\"><div class=\"mkdf-eh-item mkdf-horizontal-alignment-center\" data-item-class=\"mkdf-eh-custom-387948\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-387948\" style=\"padding: 55px 10%\">\n\t\t\t[vc_column_text]\n<h3>Chemisches Sommerpeeling<\/h3>\n<p>Das Sommerpeeling mit AHA-S\u00e4uren kann zur Verbesserung von ungleichm\u00e4\u00dfiger Pigmentierung, Akne, Vereinheitlichung und Gl\u00e4ttung von Hautstruktur und Falten verwendet werden.[\/vc_column_text][vc_empty_space][vc_column_text css=\"\"]<\/p>\n<p style=\"text-align: center; margin-top: 10px;\"><a class=\"mkdf-btn mkdf-btn-medium mkdf-btn-outline\" style=\"color: #43d5cb; padding: 14px 30px; border: 1px solid #43d5cb; border-radius: 5px; font-weight: 300;\" href=\"https:\/\/altos-klinika.cz\/de\/summer-chemical-peel\/\" target=\"_self\" rel=\"noopener\">Mehr Info<\/a><\/p>\n<p>[\/vc_column_text]\t\t<\/p><\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column_inner][vc_column_inner css=\".vc_custom_1633299493433{border-bottom-width: 0px !important;padding-top: 0% !important;padding-right: 0% !important;padding-bottom: 0% !important;padding-left: 0% !important;border-bottom-color: #ededed !important;border-bottom-style: solid !important;}\" offset=\"vc_col-lg-3 vc_col-md-6 vc_col-xs-12\"]<div class=\"mkdf-elements-holder mkdf-one-column mkdf-responsive-mode-768\"><div class=\"mkdf-eh-item mkdf-horizontal-alignment-center\" data-item-class=\"mkdf-eh-custom-237616\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-237616\" style=\"padding: 55px 10%\">\n\t\t\t[vc_column_text]\n<h3>Diamant-Mikrodermabrasion<\/h3>\n<p>Es handelt sich um eine instrumentelle Hautbehandlung nach dem Prinzip des mechanischen Peelings, bei dem die oberste Hautschicht abgetragen wird. Pflege zur Unterst\u00fctzung der Regeneration von Hautzellen, Kollagen und Elastin in der Haut. Die Haut wird durchblutet und die Poren werden aufgeweicht.[\/vc_column_text][vc_empty_space][vc_column_text css=\"\"]<\/p>\n<p style=\"text-align: center; margin-top: 10px;\"><a class=\"mkdf-btn mkdf-btn-medium mkdf-btn-outline\" style=\"color: #43d5cb; padding: 14px 30px; border: 1px solid #43d5cb; border-radius: 5px; font-weight: 300;\" href=\"https:\/\/altos-klinika.cz\/de\/diamond-microdermabrasion\/\" target=\"_self\" rel=\"noopener\">Mehr Info<\/a><\/p>\n<p>[\/vc_column_text]\t\t<\/p><\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner css=\".vc_custom_1633299472059{border-right-width: 1px !important;border-bottom-width: 0px !important;border-left-width: 1px !important;padding-top: 0% !important;padding-right: 0% !important;padding-bottom: 0% !important;padding-left: 0% !important;border-left-color: #ededed !important;border-left-style: solid !important;border-right-color: #ededed !important;border-right-style: solid !important;border-bottom-color: #ededed !important;border-bottom-style: solid !important;}\" offset=\"vc_col-lg-3 vc_col-md-6 vc_col-xs-12\"]<div class=\"mkdf-elements-holder mkdf-one-column mkdf-responsive-mode-768\"><div class=\"mkdf-eh-item mkdf-horizontal-alignment-center\" data-item-class=\"mkdf-eh-custom-887120\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-887120\" style=\"padding: 55px 10%\">\n\t\t\t[vc_column_text]\n<h3>BioRePeelCl3<\/h3>\n<p>Chemisches Peeling, das in zwei Phasen als <a href=\"https:\/\/altos-klinika.cz\/de\/mesotherapy\/\" title=\"Mesotherapie\" class=\"text-link\">Mesotherapie<\/a> und Peeling wirkt. Dank einer einzigartigen Kombination aus Vitaminen und Aminos\u00e4uren wirkt es nicht nur an der Oberfl\u00e4che, sondern auch in den unteren Hautschichten. Es hat eine biorevitalisierende und Anti-Aging-Wirkung, bek\u00e4mpft die Hautalterung, beseitigt gesch\u00e4digte Haut nach dem Sonnenbaden und hilft bei der Behandlung von Akne. Geeignet f\u00fcr alle Altersgruppen.[\/vc_column_text][vc_empty_space][vc_column_text css=\"\"]<\/p>\n<p style=\"text-align: center; margin-top: 10px;\"><a class=\"mkdf-btn mkdf-btn-medium mkdf-btn-outline\" style=\"color: #43d5cb; padding: 14px 30px; border: 1px solid #43d5cb; border-radius: 5px; font-weight: 300;\" href=\"https:\/\/altos-klinika.cz\/de\/biorepeelci3\/\" target=\"_self\" rel=\"noopener\">Mehr Info<\/a><\/p>\n<p>[\/vc_column_text]\t\t<\/p><\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row simple_background_color=\"#f4f9fd\"][vc_column][vc_empty_space][\/vc_column][\/vc_row][vc_row row_content_width=\"grid\" css=\".vc_custom_1632238008506{padding-top: 50px !important;}\"][vc_column offset=\"vc_col-lg-12\" css=\".vc_custom_1632140768248{margin-top: -8px !important;}\"]<div class=\"mkdf-elements-holder mkdf-one-column mkdf-responsive-mode-768\"><div class=\"mkdf-eh-item mkdf-horizontal-alignment-center\" data-item-class=\"mkdf-eh-custom-490915\" data-1280-1600=\"0px 10% 0px 10%\" data-1024-1280=\"0px 10% 0px 10%\" data-768-1024=\"0px 0% 0px 0%\" data-600-768=\"0 0 0 0\" data-480-600=\"0 0 0 0\" data-480=\"0 0 0 0\">\n\t<div class=\"mkdf-eh-item-inner\">\n\t\t<div class=\"mkdf-eh-item-content mkdf-eh-custom-490915\" style=\"padding: 0px 20% 0px 20%\">\n\t\t\t<div class=\"mkdf-section-title-holder mkdf-st-standard mkdf-st-title-left mkdf-st-normal-space \" style=\"text-align: center\">\n\t<div class=\"mkdf-st-inner\">\n\t\t\t\t\t<h2 class=\"mkdf-st-title\">\n\t\t\t\tBeratungsgespr\u00e4ch\t\t\t<\/h2>\n\t\t\t\t\t<\/div>\n<\/div>[vc_empty_space height=\"25px\"][vc_column_text]\n<div id=\"all-events\" class=\"ui-tabs-panel ui-corner-bottom ui-widget-content\" role=\"tabpanel\" aria-labelledby=\"ui-id-1\" aria-hidden=\"false\">\n<table class=\"tt_timetable\">\n<tbody>\n<tr class=\"row_1\">\n<td style=\"vertical-align: middle; padding: 10px 0px; width: 50%;\">Consultation with a doctor<\/td>\n<td style=\"vertical-align: middle;\"><\/td>\n<td style=\"color: #37c7be!important; vertical-align: middle;\">3 000 K\u010d<\/td>\n<\/tr>\n<tr class=\"row_gray\">\n<td style=\"vertical-align: middle; padding: 10px 0px; width: 50%;\">Check-up at the patient's request<\/td>\n<td style=\"vertical-align: middle;\"><\/td>\n<td style=\"color: #37c7be!important; vertical-align: middle;\">1 500 K\u010d<\/td>\n<\/tr>\n<tr class=\"row\">\n<td style=\"vertical-align: middle; padding: 10px 0px; width: 50%;\">Histology<\/td>\n<td style=\"vertical-align: middle;\"><\/td>\n<td style=\"color: #37c7be!important; vertical-align: middle;\">3 990 K\u010d<\/td>\n<\/tr>\n<tr class=\"row_gray\">\n<td style=\"vertical-align: middle; padding: 10px 0px; width: 50%;\" rowspan=\"2\">EMLA numbing cream<\/td>\n<td style=\"vertical-align: middle;\">big area<\/td>\n<td style=\"color: #37c7be!important; vertical-align: middle;\">1 000 K\u010d<\/td>\n<\/tr>\n<tr class=\"row_gray\">\n<td style=\"vertical-align: middle;\">small area<\/td>\n<td style=\"color: #37c7be!important; vertical-align: middle;\">500 K\u010d<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div class=\"tt_timetable small\">\n<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\n<li class=\"timetable_clearfix\">\n<div class=\"event_container\">Consultation with a doctor<\/div>\n<div class=\"value\"><span class=\"start-hour\">600 K\u010d<\/span><\/div>\n<\/li>\n<li class=\"timetable_clearfix\">\n<div class=\"event_container\">Check-up at the patient's request<\/div>\n<div class=\"value\"><span class=\"start-hour\">300 K\u010d<\/span><\/div>\n<\/li>\n<li class=\"timetable_clearfix\">\n<div class=\"event_container\">Histology<\/div>\n<div class=\"value\"><span class=\"start-hour\">2 500 K\u010d<\/span><\/div>\n<\/li>\n<li class=\"timetable_clearfix\">\n<div class=\"event_container\">Numbing cream - big area<\/div>\n<div class=\"value\"><span class=\"start-hour\">550 K\u010d<\/span><\/div>\n<\/li>\n<li class=\"timetable_clearfix\">\n<div class=\"event_container\">Numbing cream - small area<\/div>\n<div class=\"value\"><span class=\"start-hour\">200 K\u010d<\/span><\/div>\n<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_empty_space height=\"50px\"]\t\t<\/p><\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column][\/vc_row]\n<\/div> <\/body><\/html>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][\/vc_column][\/vc_row][vc_row simple_background_color=\"#fafafa\"][vc_column][vc_row_inner content_text_aligment=\"center\" css=\".vc_custom_1635020125633{padding-top: 20px !important;padding-right: 20px !important;padding-bottom: 20px !important;padding-left: 20px !important;}\"][vc_column_inner css=\".vc_custom_1633645017807{padding-top: 5% !important;padding-right: 5% !important;padding-bottom: 5% !important;padding-left: 5% !important;}\" offset=\"vc_col-lg-3 vc_col-md-6 vc_col-sm-offset-0 vc_col-xs-12\"][\/vc_column_inner][vc_column_inner [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full-width.php","meta":{"footnotes":""},"class_list":["post-18170","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/altos-klinika.cz\/de\/wp-json\/wp\/v2\/pages\/18170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/altos-klinika.cz\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/altos-klinika.cz\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/altos-klinika.cz\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/altos-klinika.cz\/de\/wp-json\/wp\/v2\/comments?post=18170"}],"version-history":[{"count":0,"href":"https:\/\/altos-klinika.cz\/de\/wp-json\/wp\/v2\/pages\/18170\/revisions"}],"wp:attachment":[{"href":"https:\/\/altos-klinika.cz\/de\/wp-json\/wp\/v2\/media?parent=18170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}